{"id":9519,"date":"2020-09-21T14:41:18","date_gmt":"2020-09-21T14:41:18","guid":{"rendered":"http:\/\/www.braplastic.com\/producto\/m675-tuerca-mariposa-rosca-laton\/"},"modified":"2020-12-18T10:35:01","modified_gmt":"2020-12-18T10:35:01","slug":"m675-tuerca-mariposa-rosca-laton","status":"publish","type":"product","link":"https:\/\/braplastic.com\/de\/producto\/m675-tuerca-mariposa-rosca-laton\/","title":{"rendered":"M675- Tuerca mariposa rosca lat\u00f3n"},"content":{"rendered":"<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"width:587px\" width=\"587\">\n<colgroup>\n<col \/>\n<col span=\"6\" \/>\t<\/colgroup>\n<tbody>\n<tr height=\"20\">\n<td height=\"20\" style=\"width:107pxheight:20px\">REFERENCIA<\/td>\n<td style=\"width:80px\">D mm<\/td>\n<td style=\"width:80px\">D1 mm<\/td>\n<td style=\"width:80px\">H mm<\/td>\n<td style=\"width:80px\">H1 mm<\/td>\n<td style=\"width:80px\">L mm<\/td>\n<td style=\"width:80px\">M<\/td>\n<\/tr>\n<tr height=\"20\">\n<td height=\"20\" style=\"height:20px\">M675 M6x11<\/td>\n<td>44<\/td>\n<td>20<\/td>\n<td>25<\/td>\n<td>17<\/td>\n<td>11<\/td>\n<td>M6<\/td>\n<\/tr>\n<tr height=\"20\">\n<td height=\"20\" style=\"height:20px\">M675 M8x14<\/td>\n<td>44<\/td>\n<td>20<\/td>\n<td>25<\/td>\n<td>17<\/td>\n<td>14<\/td>\n<td>M8<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Material: poliestireno (PS), resistente al impacto rosca lat\u00f3nColor: Negro<\/p>\n","protected":false},"featured_media":9520,"template":"","meta":{"ngg_post_thumbnail":0,"_joinchat":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M675- Tuerca mariposa rosca lat\u00f3n - Braplastic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/braplastic.com\/de\/producto\/m675-tuerca-mariposa-rosca-laton\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M675- Tuerca mariposa rosca lat\u00f3n - Braplastic\" \/>\n<meta property=\"og:description\" content=\"Material: poliestireno (PS), resistente al impacto rosca lat\u00f3nColor: Negro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/braplastic.com\/de\/producto\/m675-tuerca-mariposa-rosca-laton\/\" \/>\n<meta property=\"og:site_name\" content=\"Braplastic\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-18T10:35:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/braplastic.com\/wp-content\/uploads\/2020\/09\/m675-tuerca-mariposa-rosca-laton-455-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"127\" \/>\n\t<meta property=\"og:image:height\" content=\"120\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/braplastic.com\/#website\",\"url\":\"https:\/\/braplastic.com\/\",\"name\":\"Braplastic\",\"description\":\"Empresa de inyecci\\u00f3n de pl\\u00e1stico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/braplastic.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/braplastic.com\/de\/producto\/m675-tuerca-mariposa-rosca-laton\/#primaryimage\",\"inLanguage\":\"de\",\"url\":\"https:\/\/braplastic.com\/wp-content\/uploads\/2020\/09\/m675-tuerca-mariposa-rosca-laton-455-1.jpg\",\"contentUrl\":\"https:\/\/braplastic.com\/wp-content\/uploads\/2020\/09\/m675-tuerca-mariposa-rosca-laton-455-1.jpg\",\"width\":127,\"height\":120},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/braplastic.com\/de\/producto\/m675-tuerca-mariposa-rosca-laton\/#webpage\",\"url\":\"https:\/\/braplastic.com\/de\/producto\/m675-tuerca-mariposa-rosca-laton\/\",\"name\":\"M675- Tuerca mariposa rosca lat\\u00f3n - Braplastic\",\"isPartOf\":{\"@id\":\"https:\/\/braplastic.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/braplastic.com\/de\/producto\/m675-tuerca-mariposa-rosca-laton\/#primaryimage\"},\"datePublished\":\"2020-09-21T14:41:18+00:00\",\"dateModified\":\"2020-12-18T10:35:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/braplastic.com\/de\/producto\/m675-tuerca-mariposa-rosca-laton\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/braplastic.com\/de\/producto\/m675-tuerca-mariposa-rosca-laton\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/braplastic.com\/de\/producto\/m675-tuerca-mariposa-rosca-laton\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/braplastic.com\/de\/\",\"url\":\"https:\/\/braplastic.com\/de\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/braplastic.com\/catalogo\/\",\"url\":\"https:\/\/braplastic.com\/catalogo\/\",\"name\":\"Cat\\u00e1logo\"}},{\"@type\":\"ListItem\",\"position\":3,\"item\":{\"@id\":\"https:\/\/braplastic.com\/de\/producto\/m675-tuerca-mariposa-rosca-laton\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/braplastic.com\/de\/wp-json\/wp\/v2\/product\/9519"}],"collection":[{"href":"https:\/\/braplastic.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/braplastic.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/braplastic.com\/de\/wp-json\/wp\/v2\/media\/9520"}],"wp:attachment":[{"href":"https:\/\/braplastic.com\/de\/wp-json\/wp\/v2\/media?parent=9519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}