{"id":13458,"date":"2020-09-18T09:43:57","date_gmt":"2020-09-18T09:43:57","guid":{"rendered":"http:\/\/www.braplastic.com\/producto\/m2000-pie-clickable-para-silla-con-pasador\/"},"modified":"2020-09-18T09:43:57","modified_gmt":"2020-09-18T09:43:57","slug":"m2000-pie-clickable-para-silla-con-pasador","status":"publish","type":"product","link":"https:\/\/braplastic.com\/en\/producto\/m2000-pie-clickable-para-silla-con-pasador\/","title":{"rendered":"M2000 &#8211; Pie clickable para silla con pasador"},"content":{"rendered":"<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"width:535px\" width=\"535\">\n<colgroup>\n<col \/>\n<col span=\"5\" \/>\t<\/colgroup>\n<tbody>\n<tr height=\"20\">\n<td height=\"20\" style=\"width:135pxheight:20px\">REFERENCIA<\/td>\n<td style=\"width:80px\">A mm<\/td>\n<td style=\"width:80px\">D mm<\/td>\n<td style=\"width:80px\">d mm<\/td>\n<td style=\"width:80px\">H mm<\/td>\n<td style=\"width:80px\">L mm<\/td>\n<\/tr>\n<tr height=\"20\">\n<td height=\"20\" style=\"height:20px\">M2000 12<\/td>\n<td>16<\/td>\n<td>12<\/td>\n<td>5.3<\/td>\n<td>6<\/td>\n<td>30<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Material: &#8211; Base : LD- Polietileno (PE-LD)Color: Negro<\/p>\n","protected":false},"featured_media":10022,"template":"","meta":{"ngg_post_thumbnail":0,"_joinchat":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M2000 - Pie clickable para silla con pasador - Braplastic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/braplastic.com\/en\/producto\/m2000-pie-clickable-para-silla-con-pasador\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M2000 - Pie clickable para silla con pasador - Braplastic\" \/>\n<meta property=\"og:description\" content=\"Material: - Base : LD- Polietileno (PE-LD)Color: Negro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/braplastic.com\/en\/producto\/m2000-pie-clickable-para-silla-con-pasador\/\" \/>\n<meta property=\"og:site_name\" content=\"Braplastic\" \/>\n<meta property=\"og:image\" content=\"https:\/\/braplastic.com\/wp-content\/uploads\/2020\/09\/m2000-pie-clickable-para-silla-con-pasador-481-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"527\" \/>\n\t<meta property=\"og:image:height\" content=\"442\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/braplastic.com\/#website\",\"url\":\"https:\/\/braplastic.com\/\",\"name\":\"Braplastic\",\"description\":\"Empresa de inyecci\\u00f3n de pl\\u00e1stico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/braplastic.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/braplastic.com\/en\/producto\/m2000-pie-clickable-para-silla-con-pasador\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/braplastic.com\/wp-content\/uploads\/2020\/09\/m2000-pie-clickable-para-silla-con-pasador-481-1.jpg\",\"contentUrl\":\"https:\/\/braplastic.com\/wp-content\/uploads\/2020\/09\/m2000-pie-clickable-para-silla-con-pasador-481-1.jpg\",\"width\":527,\"height\":442},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/braplastic.com\/en\/producto\/m2000-pie-clickable-para-silla-con-pasador\/#webpage\",\"url\":\"https:\/\/braplastic.com\/en\/producto\/m2000-pie-clickable-para-silla-con-pasador\/\",\"name\":\"M2000 - Pie clickable para silla con pasador - Braplastic\",\"isPartOf\":{\"@id\":\"https:\/\/braplastic.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/braplastic.com\/en\/producto\/m2000-pie-clickable-para-silla-con-pasador\/#primaryimage\"},\"datePublished\":\"2020-09-18T09:43:57+00:00\",\"dateModified\":\"2020-09-18T09:43:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/braplastic.com\/en\/producto\/m2000-pie-clickable-para-silla-con-pasador\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/braplastic.com\/en\/producto\/m2000-pie-clickable-para-silla-con-pasador\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/braplastic.com\/en\/producto\/m2000-pie-clickable-para-silla-con-pasador\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/braplastic.com\/en\/\",\"url\":\"https:\/\/braplastic.com\/en\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/braplastic.com\/catalogo\/\",\"url\":\"https:\/\/braplastic.com\/catalogo\/\",\"name\":\"Cat\\u00e1logo\"}},{\"@type\":\"ListItem\",\"position\":3,\"item\":{\"@id\":\"https:\/\/braplastic.com\/en\/producto\/m2000-pie-clickable-para-silla-con-pasador\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/braplastic.com\/en\/wp-json\/wp\/v2\/product\/13458"}],"collection":[{"href":"https:\/\/braplastic.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/braplastic.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/braplastic.com\/en\/wp-json\/wp\/v2\/media\/10022"}],"wp:attachment":[{"href":"https:\/\/braplastic.com\/en\/wp-json\/wp\/v2\/media?parent=13458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}