{"id":10141,"date":"2020-09-18T09:43:53","date_gmt":"2020-09-18T09:43:53","guid":{"rendered":"http:\/\/www.braplastic.com\/producto\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados\/"},"modified":"2020-09-18T09:43:53","modified_gmt":"2020-09-18T09:43:53","slug":"m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados","status":"publish","type":"product","link":"https:\/\/braplastic.com\/fr\/producto\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados\/","title":{"rendered":"M1590 &#8211; Pie con base metal  deslizante para tubos cuadrados"},"content":{"rendered":"<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"width:691px\" width=\"691\">\n<colgroup>\n<col \/>\n<col span=\"7\" \/>\t<\/colgroup>\n<tbody>\n<tr height=\"20\">\n<td height=\"20\" style=\"width:131pxheight:20px\">REFERENCIA<\/td>\n<td style=\"width:80px\">\u03b1\u00b0<\/td>\n<td style=\"width:80px\">A mm<\/td>\n<td style=\"width:80px\">D mm<\/td>\n<td style=\"width:80px\">H mm<\/td>\n<td style=\"width:80px\">H1 mm<\/td>\n<td style=\"width:80px\">L mm<\/td>\n<td style=\"width:80px\">t mm<\/td>\n<\/tr>\n<tr height=\"20\">\n<td height=\"20\" style=\"height:20px\">M1590 23 \/ 17 x 17<\/td>\n<td>18 (-20)<\/td>\n<td>20 (19,5)<\/td>\n<td>23<\/td>\n<td>7<\/td>\n<td>15<\/td>\n<td>24<\/td>\n<td>1,5<\/td>\n<\/tr>\n<tr height=\"20\">\n<td height=\"20\" style=\"height:20px\">M1590 27 \/ 17 x 17<\/td>\n<td>25<\/td>\n<td>20 (19,5)<\/td>\n<td>27<\/td>\n<td>7<\/td>\n<td>15<\/td>\n<td>24<\/td>\n<td>1,5<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Material: &#8211; Eje: Polietileno (PE) &#8211; Base deslizante :  Acero niquelado &#8211; Elementos conectores: Acero y PVC Color: Negro<\/p>\n","protected":false},"featured_media":10142,"template":"","meta":{"ngg_post_thumbnail":0,"_joinchat":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M1590 - Pie con base metal deslizante para tubos cuadrados - Braplastic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/braplastic.com\/fr\/producto\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M1590 - Pie con base metal deslizante para tubos cuadrados - Braplastic\" \/>\n<meta property=\"og:description\" content=\"Material: - Eje: Polietileno (PE) - Base deslizante : Acero niquelado - Elementos conectores: Acero y PVC Color: Negro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/braplastic.com\/fr\/producto\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados\/\" \/>\n<meta property=\"og:site_name\" content=\"Braplastic\" \/>\n<meta property=\"og:image\" content=\"https:\/\/braplastic.com\/wp-content\/uploads\/2020\/09\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados-467-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"137\" \/>\n\t<meta property=\"og:image:height\" content=\"118\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/braplastic.com\/#website\",\"url\":\"https:\/\/braplastic.com\/\",\"name\":\"Braplastic\",\"description\":\"Empresa de inyecci\\u00f3n de pl\\u00e1stico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/braplastic.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/braplastic.com\/fr\/producto\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/braplastic.com\/wp-content\/uploads\/2020\/09\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados-467-1.jpg\",\"contentUrl\":\"https:\/\/braplastic.com\/wp-content\/uploads\/2020\/09\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados-467-1.jpg\",\"width\":137,\"height\":118},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/braplastic.com\/fr\/producto\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados\/#webpage\",\"url\":\"https:\/\/braplastic.com\/fr\/producto\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados\/\",\"name\":\"M1590 - Pie con base metal deslizante para tubos cuadrados - Braplastic\",\"isPartOf\":{\"@id\":\"https:\/\/braplastic.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/braplastic.com\/fr\/producto\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados\/#primaryimage\"},\"datePublished\":\"2020-09-18T09:43:53+00:00\",\"dateModified\":\"2020-09-18T09:43:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/braplastic.com\/fr\/producto\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/braplastic.com\/fr\/producto\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/braplastic.com\/fr\/producto\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/braplastic.com\/fr\/\",\"url\":\"https:\/\/braplastic.com\/fr\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/braplastic.com\/catalogo\/\",\"url\":\"https:\/\/braplastic.com\/catalogo\/\",\"name\":\"Cat\\u00e1logo\"}},{\"@type\":\"ListItem\",\"position\":3,\"item\":{\"@id\":\"https:\/\/braplastic.com\/fr\/producto\/m1590-pie-con-base-metal-deslizante-para-tubos-cuadrados\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/braplastic.com\/fr\/wp-json\/wp\/v2\/product\/10141"}],"collection":[{"href":"https:\/\/braplastic.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/braplastic.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/braplastic.com\/fr\/wp-json\/wp\/v2\/media\/10142"}],"wp:attachment":[{"href":"https:\/\/braplastic.com\/fr\/wp-json\/wp\/v2\/media?parent=10141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}