{"id":12141,"date":"2020-09-18T09:43:16","date_gmt":"2020-09-18T09:43:16","guid":{"rendered":"http:\/\/www.braplastic.com\/producto\/s191-cordon-cuadrado-de-espuma-de-silicona\/"},"modified":"2020-09-18T09:43:16","modified_gmt":"2020-09-18T09:43:16","slug":"s191-cordon-cuadrado-de-espuma-de-silicona","status":"publish","type":"product","link":"https:\/\/braplastic.com\/fr\/producto\/s191-cordon-cuadrado-de-espuma-de-silicona\/","title":{"rendered":"S191 &#8211; Cord\u00f3n cuadrado de espuma de silicona"},"content":{"rendered":"<\/p>\n<\/p>\n<table border=\"0\" cellpadding=\"0\" cellspacing=\"0\" style=\"width: 972px height: 90px\" width=\"972\">\n<colgroup>\n<col span=\"3\" \/>\t<\/colgroup>\n<tbody>\n<tr height=\"20\">\n<td align=\"left\" height=\"20\" style=\"width: 80px height: 20px\"><strong>Referencia<\/strong><\/td>\n<td style=\"width: 80px\"><strong>D mm<\/strong><\/td>\n<td style=\"width: 80px\"><strong>L mts.<\/strong><\/td>\n<\/tr>\n<tr height=\"20\">\n<td align=\"left\" height=\"20\" style=\"height: 20px\">S191-10&#215;10<\/td>\n<td>10&#215;10<\/td>\n<td>25,00<\/td>\n<\/tr>\n<tr height=\"20\">\n<td align=\"left\" height=\"20\" style=\"height: 20px\">S191-12&#215;12<\/td>\n<td>12&#215;12<\/td>\n<td>25,00<\/td>\n<\/tr>\n<tr height=\"20\">\n<td align=\"left\" height=\"20\" style=\"height: 20px\">S191-20&#215;20<\/td>\n<td>20&#215;20<\/td>\n<td>25,00<\/td>\n<\/tr>\n<\/tbody>\n<\/table><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Material: Espuma de Silicona   &#8211;   Color: Varios<\/p>\n","protected":false},"featured_media":12142,"template":"","meta":{"ngg_post_thumbnail":0,"_joinchat":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>S191 - Cord\u00f3n cuadrado de espuma de silicona - Braplastic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/braplastic.com\/fr\/producto\/s191-cordon-cuadrado-de-espuma-de-silicona\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S191 - Cord\u00f3n cuadrado de espuma de silicona - Braplastic\" \/>\n<meta property=\"og:description\" content=\"Material: Espuma de Silicona  -  Color: Varios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/braplastic.com\/fr\/producto\/s191-cordon-cuadrado-de-espuma-de-silicona\/\" \/>\n<meta property=\"og:site_name\" content=\"Braplastic\" \/>\n<meta property=\"og:image\" content=\"https:\/\/braplastic.com\/wp-content\/uploads\/2020\/09\/154201519052583046p.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"287\" \/>\n\t<meta property=\"og:image:height\" content=\"235\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/braplastic.com\/#website\",\"url\":\"https:\/\/braplastic.com\/\",\"name\":\"Braplastic\",\"description\":\"Empresa de inyecci\\u00f3n de pl\\u00e1stico\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/braplastic.com\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/braplastic.com\/fr\/producto\/s191-cordon-cuadrado-de-espuma-de-silicona\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/braplastic.com\/wp-content\/uploads\/2020\/09\/154201519052583046p.jpg\",\"contentUrl\":\"https:\/\/braplastic.com\/wp-content\/uploads\/2020\/09\/154201519052583046p.jpg\",\"width\":287,\"height\":235},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/braplastic.com\/fr\/producto\/s191-cordon-cuadrado-de-espuma-de-silicona\/#webpage\",\"url\":\"https:\/\/braplastic.com\/fr\/producto\/s191-cordon-cuadrado-de-espuma-de-silicona\/\",\"name\":\"S191 - Cord\\u00f3n cuadrado de espuma de silicona - Braplastic\",\"isPartOf\":{\"@id\":\"https:\/\/braplastic.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/braplastic.com\/fr\/producto\/s191-cordon-cuadrado-de-espuma-de-silicona\/#primaryimage\"},\"datePublished\":\"2020-09-18T09:43:16+00:00\",\"dateModified\":\"2020-09-18T09:43:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/braplastic.com\/fr\/producto\/s191-cordon-cuadrado-de-espuma-de-silicona\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/braplastic.com\/fr\/producto\/s191-cordon-cuadrado-de-espuma-de-silicona\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/braplastic.com\/fr\/producto\/s191-cordon-cuadrado-de-espuma-de-silicona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/braplastic.com\/fr\/\",\"url\":\"https:\/\/braplastic.com\/fr\/\",\"name\":\"Portada\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/braplastic.com\/catalogo\/\",\"url\":\"https:\/\/braplastic.com\/catalogo\/\",\"name\":\"Cat\\u00e1logo\"}},{\"@type\":\"ListItem\",\"position\":3,\"item\":{\"@id\":\"https:\/\/braplastic.com\/fr\/producto\/s191-cordon-cuadrado-de-espuma-de-silicona\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/braplastic.com\/fr\/wp-json\/wp\/v2\/product\/12141"}],"collection":[{"href":"https:\/\/braplastic.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/braplastic.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/braplastic.com\/fr\/wp-json\/wp\/v2\/media\/12142"}],"wp:attachment":[{"href":"https:\/\/braplastic.com\/fr\/wp-json\/wp\/v2\/media?parent=12141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}